{"id":75425,"date":"2016-07-27T09:00:40","date_gmt":"2016-07-27T12:00:40","guid":{"rendered":"http:\/\/bestcars.uol.com.br\/bc\/?p=75425"},"modified":"2016-08-01T09:43:46","modified_gmt":"2016-08-01T12:43:46","slug":"teste-fiat-mobi-way-on-forte-em-suspensao-fraco-em-desempenho","status":"publish","type":"post","link":"https:\/\/autolivraria.com.br\/bc\/informe-se\/avaliacao\/teste-fiat-mobi-way-on-forte-em-suspensao-fraco-em-desempenho\/","title":{"rendered":"Mobi Way: forte em suspens\u00e3o, fraco em desempenho"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-75425 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-10.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"696\" height=\"464\" src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-10-696x464.jpg\" class=\"attachment-large size-large\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h2>O novo pequeno passa por avalia\u00e7\u00e3o com medi\u00e7\u00f5es e revela o que pode oferecer diante de VW Up e outros<\/h2>\n<p><em>Texto e fotos: Fabr\u00edcio Samah\u00e1<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Afinal, a que veio o Fiat Mobi? Vale a pena optar pelo novo hatchback de Betim, MG, em vez dos concorrentes estabelecidos? S\u00e3o perguntas a serem respondidas com uma avalia\u00e7\u00e3o completa, que efetuamos com a vers\u00e3o de topo Way On, submetida tamb\u00e9m a nossas medi\u00e7\u00f5es de desempenho e consumo. A linha Mobi come\u00e7a em R$ 31.900, pre\u00e7o da vers\u00e3o Easy, mas chega a R$ 43.800 no Way On, que n\u00e3o oferece opcionais (o sufixo On j\u00e1 indica acr\u00e9scimo de acess\u00f3rios ao Way de R$ 39.300, como se fosse um pacote).<\/p>\n<p>Os equipamentos de s\u00e9rie abrangem ajuste el\u00e9trico dos retrovisores, alarme antifurto volum\u00e9trico, ar-condicionado, banco do motorista com regulagem de altura, banco traseiro bipartido com ajuste de inclina\u00e7\u00e3o, cintos laterais traseiros retr\u00e1teis, computador de bordo, controle el\u00e9trico de vidros dianteiros e travas e controle remoto de travamento, dire\u00e7\u00e3o com assist\u00eancia hidr\u00e1ulica, far\u00f3is de neblina, limpador e desemba\u00e7ador do vidro traseiro, r\u00e1dio\/MP3 com comandos no volante, rodas de alum\u00ednio de 14 polegadas, sensores de estacionamento traseiros\u00a0e volante com regulagem de altura. As bolsas infl\u00e1veis s\u00e3o apenas frontais.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-2' class='gallery galleryid-75425 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-04.jpg'><img decoding=\"async\" width=\"696\" height=\"464\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-04-696x464.jpg\" class=\"attachment-large size-large lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 696px; --smush-placeholder-aspect-ratio: 696\/464;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-3' class='gallery galleryid-75425 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-12.jpg'><img decoding=\"async\" width=\"340\" height=\"227\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-12-340x227.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/227;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-11.jpg'><img decoding=\"async\" width=\"340\" height=\"227\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-11-340x227.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/227;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: center;\"><em>Tampa traseira de vidro \u00e9 o toque mais original do Mobi; vers\u00e3o Way vem com 15 mm a mais de altura de rodagem, para-choque espec\u00edfico e rodas de alum\u00ednio<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Em que pese a sensa\u00e7\u00e3o de ser um Uno encurtado e reestilizado, o Mobi \u00e9 um novo carro em quase toda a estrutura, garante o fabricante. O que eles t\u00eam em comum, al\u00e9m de alguns componentes internos, \u00e9 o trem de for\u00e7a com o conhecido motor Fire de 1,0 litro, quatro cilindros e duas v\u00e1lvulas por cilindro \u2014 a mais moderna unidade GSE de tr\u00eas cilindros deve estrear este ano no Uno, mas pode levar mais algum tempo a chegar ao novo carro.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>A tampa traseira de vidro \u00e9 uma boa ideia em economia de espa\u00e7o e peso, mas a Fiat desenhou uma porta pequena e elevou a base de acesso<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>As formas robustas do Mobi, com cap\u00f4 volumoso, grandes far\u00f3is e para-lamas bojudos, v\u00eam acentuadas no Way por molduras nos arcos de roda, barras de teto e para-choque dianteiro pr\u00f3prio, al\u00e9m de rodas diferenciadas. Um item in\u00e9dito em carro nacional \u00e9 a tampa traseira toda de vidro, solu\u00e7\u00e3o que o <a href=\"https:\/\/autolivraria.com.br\/bc\/tag\/up\" target=\"_blank\">Volkswagen Up<\/a> usa na Europa, mas foi abolida aqui.<\/p>\n<p>\u00c9 uma boa ideia do ponto de vista de economia de espa\u00e7o (o vidro \u00e9 v\u00e1rios cent\u00edmetros mais estreito que uma porta de a\u00e7o) e de peso, mas fica o natural questionamento sobre sua vulnerabilidade a impactos pela traseira. Para reduzir o risco de danos e tamb\u00e9m aumentar a resist\u00eancia estrutural da regi\u00e3o, a Fiat desenhou uma porta pequena e elevou a base de acesso ao compartimento de bagagem. O resultado \u00e9 um acesso bem menos confort\u00e1vel que (por exemplo) no Uno para colocar cargas volumosas ou retirar o estepe.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-4' class='gallery galleryid-75425 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-05.jpg'><img decoding=\"async\" width=\"696\" height=\"464\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-05-696x464.jpg\" class=\"attachment-large size-large lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 696px; --smush-placeholder-aspect-ratio: 696\/464;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-5' class='gallery galleryid-75425 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-13.jpg'><img decoding=\"async\" width=\"340\" height=\"227\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-13-340x227.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/227;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-pm.jpg'><img decoding=\"async\" width=\"340\" height=\"227\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-pm-340x227.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/227;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: center;\"><em>Cap\u00f4, para-lamas e lanternas traseiras volumosos deixam o novo Fiat com aspecto robusto; tampa pequena d\u00e1 acesso a um limitado porta-malas de 215 litros<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O ambiente interno do Mobi \u00e9 familiar a quem conhece o &#8220;irm\u00e3o maior&#8221;, embora painel e bancos sejam outros. A impress\u00e3o positiva para um carro do segmento de entrada vem da boa escolha de texturas dos pl\u00e1sticos e da aus\u00eancia de chapas aparentes. Como no Up os bancos dianteiros usam encostos inteiri\u00e7os, sem apoio de cabe\u00e7a separado, o que funciona bem. No entanto, por serem curtos para as coxas e estreitos no assento e no encosto, oferecem menos conforto que os do Uno e chegam a incomodar em trajetos longos. Uma pena, pois no restante a posi\u00e7\u00e3o do motorista foi bem definida, os pedais ficam \u00e0 direita em grau toler\u00e1vel e h\u00e1 ajustes de altura para banco e volante.<\/p>\n<p>&nbsp;<\/p>\n<div class='code-block code-block-13' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<!-- AL-quadrado -->\n<ins class=\"adsbygoogle\"\n     style=\"display:block\"\n     data-ad-client=\"ca-pub-1914799802606213\"\n     data-ad-slot=\"5683066082\"\n     data-ad-format=\"auto\"\n     data-full-width-responsive=\"true\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n\n<p>&nbsp;<\/p>\n<p>No quadro de instrumentos do Way On h\u00e1 um mostrador digital com computador de bordo, \u00edcone sugestivo para trocas de marcha (para cima e para baixo) e indicador de temperatura externa. O simples sistema de \u00e1udio, com o r\u00e1dio\/MP3 (sem toca-CDs) conhecido do Uno, traz interface <a href=\"https:\/\/autolivraria.com.br\/bc\/glossario-b\/#blue\" target=\"_blank\">Bluetooth<\/a> para telefone celular e conex\u00f5es USB e auxiliar. A qualidade sonora das mais pobres est\u00e1 no esperado da categoria.<\/p>\n<p>O controle el\u00e9trico de vidros (apenas dianteiros, algo a ser repensado) tem <a href=\"https:\/\/autolivraria.com.br\/bc\/glossario-u\/#umto\" target=\"_blank\">fun\u00e7\u00e3o um-toque<\/a>, <a href=\"https:\/\/autolivraria.com.br\/bc\/glossario-t\/#temp\" target=\"_blank\">temporizador<\/a> e comando a dist\u00e2ncia de abertura e fechamento. Os far\u00f3is de refletor \u00fanico surpreendem pela efic\u00e1cia no facho baixo, embora a comuta\u00e7\u00e3o para alto prejudique muito a ilumina\u00e7\u00e3o mais pr\u00f3xima (atenuado com o uso dos far\u00f3is de neblina).<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-6' class='gallery galleryid-75425 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-interior.jpg'><img decoding=\"async\" width=\"696\" height=\"464\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-interior-696x464.jpg\" class=\"attachment-large size-large lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 696px; --smush-placeholder-aspect-ratio: 696\/464;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: center;\"><em>Acabamento do interior, com pl\u00e1sticos aceit\u00e1veis e sem chapas expostas, e posi\u00e7\u00e3o de dirigir do Mobi est\u00e3o\u00a0adequados ao segmento; r\u00e1dio\/MP3 vem de s\u00e9rie<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Outros bons detalhes s\u00e3o aviso para porta mal fechada, banco traseiro com duas posi\u00e7\u00f5es de encosto (a mais vertical favorece o espa\u00e7o para bagagem com sacrif\u00edcio do conforto), bolsas nos encostos dianteiros, comando interno para tampa traseira e portinhola do tanque, espelho nos para-s\u00f3is, para-brisa com faixa degrad\u00ea, pintura do cofre do motor como a da carroceria (requinte que muitos BMWs n\u00e3o t\u00eam), repetidores laterais das luzes de dire\u00e7\u00e3o, retrovisores externos <a href=\"https:\/\/autolivraria.com.br\/bc\/glossario-c\/#conv\" target=\"_blank\">convexos<\/a>\u00a0e bem amplos, temporizador de far\u00f3is e da luz interna, tr\u00eas al\u00e7as de teto e vidros traseiros que descem por inteiro.<\/p>\n<p>Pontos que merecem corre\u00e7\u00e3o: gira-se a chave em posi\u00e7\u00e3o antinatural para a partida, a tampa traseira n\u00e3o tem ma\u00e7aneta (exige uso da alavanca ou da chave) e sua abertura pela chave com o carro travado faz o alarme disparar, h\u00e1 pouco espa\u00e7o para os objetos do dia a dia e faltam cinto de tr\u00eas pontos e encosto de cabe\u00e7a para o passageiro central atr\u00e1s, alerta para uso de cinto, ilumina\u00e7\u00e3o na parte traseira da cabine e no porta-malas e <a href=\"https:\/\/autolivraria.com.br\/bc\/glossario-p\/#prea\" target=\"_blank\">preaquecimento de \u00e1lcool<\/a> para partida a frio. Tamb\u00e9m n\u00e3o faria mal um volante mais macio ao toque e, como em muitos carros recentes, as largas colunas dianteiras prejudicam o campo visual.<\/p>\n<table border=\"0\">\n<tbody>\n<tr>\n<td><a href='https:\/\/autolivraria.com.br\/bc\/informe-se\/avaliacao\/teste-fiat-mobi-way-on-forte-em-suspensao-fraco-em-desempenho\/2\/' class='small-button smallsilver'>Pr\u00f3xima parte<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><!--nextpage--><\/p>\n<div id='gallery-7' class='gallery galleryid-75425 gallery-columns-3 gallery-size-222px'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-banco1.jpg'><img decoding=\"async\" width=\"222\" height=\"278\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-banco1-222x278.jpg\" class=\"attachment-222px size-222px lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/278;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-banco2.jpg'><img decoding=\"async\" width=\"222\" height=\"278\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-banco2-222x278.jpg\" class=\"attachment-222px size-222px lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/278;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-console.jpg'><img decoding=\"async\" width=\"222\" height=\"278\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-console-222x278.jpg\" class=\"attachment-222px size-222px lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/278;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: center;\"><em>Bancos com encosto integrado n\u00e3o s\u00e3o problema: os inc\u00f4modos s\u00e3o o desconforto dos dianteiros e o espa\u00e7o traseiro muito limitado para pernas e ombros<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O calcanhar de Aquiles do pequeno Fiat \u00e9, sem d\u00favida, o espa\u00e7o no banco traseiro ex\u00edguo em largura (levar tr\u00eas adultos beira o imposs\u00edvel) e no v\u00e3o para pernas, embora adequado em altura. Um passageiro de 1,75 metro j\u00e1 fica com os joelhos quase no encosto, atr\u00e1s de um motorista de mesma estatura. O encosto \u00e9 mais vertical que o usual e o assento deixa as coxas mal apoiadas, o que cansa em longos trajetos. Mesmo que o padr\u00e3o no segmento de hatches pequenos seja certo desconforto, o Mobi est\u00e1 entre os mais limitados.\u00a0De fato, sem recorrer a uma carroceria bem alta, seria imposs\u00edvel reduzir em 24,5 cent\u00edmetros o comprimento em rela\u00e7\u00e3o ao Uno sem sacrificar ocupantes e&#8230; bagagem.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>Pisa-se pouco no acelerador e a borboleta abre muito, o que deixa o carro \u00e1gil: a m\u00e1scara cai quando se acelera mais e nada acontece<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Sim, a observa\u00e7\u00e3o vale tamb\u00e9m para o compartimento de 215 litros, menor em 70 l que o do Up, de comprimento parecido. Uma caixa organizadora no fundo tem duas fun\u00e7\u00f5es: a \u00f3bvia, de guardar objetos com uma divis\u00e3o que pode ser reposicionada, e a outra de tornar mais alta e acess\u00edvel a base do compartimento. Sem ela, o assoalho fica muito fundo \u2014 e nem luz existe para ajudar a procurar objetos perdidos. Se for removida ganham-se 20 litros de espa\u00e7o. O estepe interno segue a medida dos outros pneus, com roda de a\u00e7o.<\/p>\n<p>&nbsp;<\/p>\n<h2>Veterano motor decepciona na pista<\/h2>\n<p>Com motor id\u00eantico e certo aproveitamento de plataforma, o Mobi n\u00e3o poderia mesmo ser muito diferente do Uno para quem dirige. At\u00e9 em peso eles est\u00e3o muito pr\u00f3ximos: 966 kg o Way On, apenas 14 kg abaixo do Uno Way de mesmo motor. O Fire desenvolve pot\u00eancia de 73\/75 cv e torque de 9,5\/9,9 m.kgf (com gasolina e \u00e1lcool, na ordem): valores apropriados \u00e0 categoria e a seu peso, embora menos expressivos que nos modernos tr\u00eas-cilindros, que chegam a ter 13 cv a mais no caso do <a href=\"https:\/\/autolivraria.com.br\/bc\/tag\/ka\" target=\"_blank\">Ford Ka<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-8' class='gallery galleryid-75425 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-instr.jpg'><img decoding=\"async\" width=\"340\" height=\"226\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-instr-340x226.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/226;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-det03.jpg'><img decoding=\"async\" width=\"340\" height=\"226\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-det03-340x226.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/226;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-det02.jpg'><img decoding=\"async\" width=\"340\" height=\"226\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-det02-340x226.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/226;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-det10.jpg'><img decoding=\"async\" width=\"340\" height=\"226\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-det10-340x226.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/226;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: center;\"><em>Instrumentos compactos com indicador para troca de marcha, comandos de \u00e1udio no volante, controle um-toque para vidros (s\u00f3 dianteiros), espelho para vigiar as crian\u00e7as<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O veterano quatro-cilindros tem funcionamento macio, qualidade que os tr\u00eas-cilindros raramente alcan\u00e7am, e seu n\u00edvel de ru\u00eddo est\u00e1 dentro da m\u00e9dia: pode-se viajar a 120 km\/h sem maior inc\u00f4modo, apesar dos barulhos gerais transmitidos \u00e0 cabine. Barulhento de verdade ele se torna acima de 5.000 rpm, mas o acelerador foi suave nas aberturas e fechamentos, ao contr\u00e1rio da vers\u00e3o Like On dirigida no <a href=\"https:\/\/autolivraria.com.br\/bc\/informe-se\/avaliacao\/teste-ao-volante-novo-fiat-mobi-nao-e-tao-novo-assim\/\" target=\"_blank\">lan\u00e7amento<\/a>. O desempenho, por\u00e9m, \u00e9 menor do que as rea\u00e7\u00f5es iniciais fazem parecer.<\/p>\n<p>&nbsp;<\/p>\n<div class='code-block code-block-7' style='margin: 28px auto; text-align: center; display: block; clear: both;'>\n<br>\n<div align=\"center\">\n<a target=\"_blank\" href=\"https:\/\/bestcars.com.br\/bc\/\">\n<img decoding=\"async\" data-src=\"https:\/\/bestcars.com.br\/bc\/wp-content\/uploads\/2021\/07\/Auto-Livraria-450x300-quadros.jpg\" alt=\"Auto Livraria\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a>\n<\/div>\n<br><\/div>\n\n<p>&nbsp;<\/p>\n<p>Como assim? Tem ficado evidente em alguns modelos (os da Hyundai, em sua maioria, s\u00e3o exemplos) que a abertura da borboleta de acelera\u00e7\u00e3o \u00e9 muito maior\u00a0que a do solicitada pelo pedal acelerador. Pisa-se pouco e a borboleta abre muito, o que deixa o carro \u00e1gil no uso urbano e transmite sensa\u00e7\u00e3o de pot\u00eancia. Al\u00e9m do maior consumo, o problema \u00e9 que a m\u00e1scara cai quando se acelera mais (ou mesmo tudo) e nada acontece: como o motor j\u00e1 estava pr\u00f3ximo de obter toda a pot\u00eancia dispon\u00edvel naquela rota\u00e7\u00e3o, o motorista acaba decepcionado \u2014 ou descobre que a ultrapassagem ser\u00e1 mais apertada do que imaginava.<\/p>\n<p>A comprova\u00e7\u00e3o veio nas medi\u00e7\u00f5es em nossa pista, onde o Mobi acelerou de 0 a 100 km\/h em modestos 17,1 segundos: qualquer um esperaria menos ao ver sua rapidez no tr\u00e2nsito com o enganoso acelerador. Tamb\u00e9m n\u00e3o foi t\u00e3o econ\u00f4mico: 13,6 km\/l no trajeto urbano leve e 11,3 km\/l no rodovi\u00e1rio com gasolina s\u00e3o marcas bem abaixo das obtidas pelo Move Up (<em>veja abaixo os n\u00fameros, an\u00e1lise detalhada e compara\u00e7\u00e3o aos advers\u00e1rios<\/em>).<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-9' class='gallery galleryid-75425 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-motor-1.jpg'><img decoding=\"async\" width=\"340\" height=\"226\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-motor-1-340x226.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/226;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-14.jpg'><img decoding=\"async\" width=\"340\" height=\"227\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-14-340x227.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/227;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: center;\"><em>Motor igual ao do Uno \u00e9 muito suave, mas decepciona em desempenho; far\u00f3is de refletor \u00fanico iluminam bem\u00a0no facho baixo; os de neblina s\u00e3o de s\u00e9rie<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>No comando da transmiss\u00e3o, relativamente suave e preciso, ou nas boas respostas da dire\u00e7\u00e3o (que poderia adotar assist\u00eancia el\u00e9trica para menor consumo de energia), o Mobi repete em grande parte as sensa\u00e7\u00f5es de dirigir o Uno. O mesmo vale para a suspens\u00e3o, que no Way vem com altura de rodagem elevada em 15 mm e calibra\u00e7\u00e3o espec\u00edfica. Os pneus 175\/65 R 14 de asfalto, Pirelli Cinturato P1 no carro avaliado, s\u00e3o os mesmos da vers\u00e3o Like.<\/p>\n<p>Com ajuste macio e longo curso, a suspens\u00e3o garante um rodar confort\u00e1vel, com destaque para a absor\u00e7\u00e3o de grandes irregularidades (como buracos mais fundos em estradas de terra) e a passagem tranquila por lombadas de qualquer tipo. Pequenos impactos s\u00e3o mais transmitidos, ainda em patamar muito bom para um carro pequeno, e o v\u00e3o livre do solo (171 mm) \u00e9 suficiente para rodar em quase qualquer terreno aberto \u00e0 circula\u00e7\u00e3o no Brasil sem risco de raspar alguma parte inferior. O sobrenome Way n\u00e3o foi em v\u00e3o.<\/p>\n<table border=\"0\">\n<tbody>\n<tr>\n<td><a href='https:\/\/autolivraria.com.br\/bc\/informe-se\/avaliacao\/teste-fiat-mobi-way-on-forte-em-suspensao-fraco-em-desempenho\/3\/' class='small-button smallsilver'>Pr\u00f3xima parte<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<div class='et-box et-shadow'>\n\t\t\t\t\t<div class='et-box-content'><h2>Desempenho e consumo<\/h2>\n<p>Testado com gasolina, como o recebemos do fabricante, o Mobi ficou distante do \u00edndice oficial para acelera\u00e7\u00e3o de 0 a 100 km\/h: 17,1 segundos ante 14,6 s declarados. Com essa marca, est\u00e1 bem atr\u00e1s do Ford Ka SEL (14,4 s com \u00e1lcool) e do VW Move Up (13,5 s com \u00e1lcool, 15 s com gasolina) e empatado com o Nissan March SV (17,1 s com \u00e1lcool).<\/p>\n<p>Chama aten\u00e7\u00e3o no Fiat a demora para alcan\u00e7ar 120 km\/h: 27,9 s, exatos 10,8 s a mais que os 100 km\/h. A explica\u00e7\u00e3o est\u00e1 no c\u00e1lculo da transmiss\u00e3o, pelo qual a terceira atinge o limite de giros (6.500 rpm) pouco antes dessa velocidade real e requer mudan\u00e7a para quarta. O motor ent\u00e3o cai de rota\u00e7\u00e3o e demora a &#8220;empurrar&#8221; o carro com alguma decis\u00e3o. Apesar de tamb\u00e9m n\u00e3o alcan\u00e7arem 120 em terceira, o Up com gasolina levou mais 7,9 s para o trecho 100-120 e o March mais 8,3 s, tempos razo\u00e1veis. O Ka, que pode ir a 120 naquela marcha e dispensa a troca para quarta, fez em 6,2 s.<\/p>\n<p>Esse c\u00e1lculo tamb\u00e9m explica a aus\u00eancia das usuais medi\u00e7\u00f5es de 60 a 120 km\/h e de 80 a 120 km\/h em terceira marcha para o Fiat. Somado ao baixo desempenho do motor, isso levou a prova de 60 a 120 a ser feita em sonolentos 31,8 s, tempo dos piores j\u00e1 obtidos em nossos testes (o Up fez em 22,3 s, o Ka em 24,2 s e o March em 25,4 s). Claro que no mundo real o motorista poder\u00e1 concluir uma ultrapassagem em terceira com o motor no limite ou mudar para quarta para continuar a ganhar velocidade: nesse caso chegar\u00e1 mais r\u00e1pido aos 120.<\/p>\n<p>N\u00e3o bastasse andar bem menos, o Mobi ainda consome muito\u00a0mais que o\u00a0Move Up, ambos com gasolina: rodou 29% a menos por litro que o VW no trajeto urbano leve, 21% a menos no urbano exigente e 24% a menos no percurso rodovi\u00e1rio. Ka e March foram medidos com \u00e1lcool, o que dificulta\u00a0a compara\u00e7\u00e3o. N\u00e3o estranhe o consumo bem mais alto em rodovia que no trajeto urbano leve: isso \u00e9 comum em carros pouco potentes, que s\u00e3o mais exigidos para manter 120 km\/h constantes com ar-condicionado ligado, enquanto economizam na cidade com os pequenos motores.<\/p><\/div><\/div>\n<p>&nbsp;<\/p>\n<div class='et-box et-shadow'>\n\t\t\t\t\t<div class='et-box-content'><table id=\"table6087\" border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"3\">\n<tbody>\n<tr>\n<td colspan=\"2\" valign=\"top\"><strong>Acelera\u00e7\u00e3o<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\" valign=\"top\">0 a 100 km\/h<\/td>\n<td style=\"width: 50%;\" valign=\"top\">17,1 s<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">0 a 120 km\/h<\/td>\n<td valign=\"top\">27,9 s<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">0 a 400 m<\/td>\n<td valign=\"top\">20,6 s<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\"><strong>Retomada<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">60 a 100 km\/h (3\u00aa.)<\/td>\n<td valign=\"top\">13,3 s<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">60 a 100 km\/h (4\u00aa.)<\/td>\n<td valign=\"top\">19,4 s<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">60 a 120 km\/h (3\u00aa.)<\/td>\n<td valign=\"top\">NA<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">60 a 120 km\/h (4\u00aa.)<\/td>\n<td valign=\"top\">31,8 s<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">80 a 120 km\/h (3\u00aa.)<\/td>\n<td valign=\"top\">NA<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">80 a 120 km\/h (4\u00aa.)<\/td>\n<td valign=\"top\">24,5 s<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\"><strong>Consumo<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Trajeto leve em cidade<\/td>\n<td valign=\"top\">13,6 km\/l<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Trajeto exigente em cidade<\/td>\n<td valign=\"top\">7,5 km\/l<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Trajeto em rodovia<\/td>\n<td valign=\"top\">11,3 km\/l<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\"><strong>Autonomia<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Trajeto leve em cidade<\/td>\n<td valign=\"top\">575 km<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Trajeto exigente em cidade<\/td>\n<td valign=\"top\">317 km<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Trajeto em rodovia<\/td>\n<td valign=\"top\">478 km<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"100%\">Testes efetuados com gasolina; NA = n\u00e3o aplic\u00e1vel; <a title=\"M\u00e9todos de medi\u00e7\u00e3o de desempenho e consumo\" href=\"https:\/\/autolivraria.com.br\/bc\/metodos-de-medicao-de-desempenho-e-consumo\/\" target=\"_blank\">conhe\u00e7a nossos m\u00e9todos de medi\u00e7\u00e3o<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div><\/div>\n<p>&nbsp;<\/p>\n<div class='et-box et-shadow'>\n\t\t\t\t\t<div class='et-box-content'><h2>Dados do fabricante<\/h2>\n<table id=\"table6089\" border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"3\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\" valign=\"top\">Velocidade m\u00e1xima<\/td>\n<td style=\"width: 50%;\" valign=\"top\">151\/152 km\/h<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Acelera\u00e7\u00e3o de 0 a 100 km\/h<\/td>\n<td valign=\"top\">14,6\/13,8 s<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Consumo em cidade<\/td>\n<td valign=\"top\">11,9\/8,4 km\/l<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Consumo em rodovia<\/td>\n<td valign=\"top\">13,3\/9,2 km\/l<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\">Gasolina\/\u00e1lcool; consumo conforme padr\u00f5es do Inmetro<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div><\/div>\n<table border=\"0\">\n<tbody>\n<tr>\n<td><a href='https:\/\/autolivraria.com.br\/bc\/informe-se\/avaliacao\/teste-fiat-mobi-way-on-forte-em-suspensao-fraco-em-desempenho\/3\/' class='small-button smallsilver'>Pr\u00f3xima parte<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><!--nextpage--><\/p>\n<div id='gallery-10' class='gallery galleryid-75425 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-01.jpg'><img decoding=\"async\" width=\"696\" height=\"464\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-01-696x464.jpg\" class=\"attachment-large size-large lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 696px; --smush-placeholder-aspect-ratio: 696\/464;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: center;\"><em>Embora o acelerador engane, o Mobi n\u00e3o \u00e9 potente (17 s para ir de 0 a 100 km\/h) e consome bem mais que o Up: faz falta um motor mais moderno<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Claro que um carro estreito, alto e com suspens\u00e3o macia n\u00e3o seria um primor de estabilidade, mas o Mobi pode ser dirigido normalmente. Apesar de haver mais movimentos e inclina\u00e7\u00e3o de carroceria que em modelos mais baixos e\/ou firmes, o motorista acostuma-se logo a suas rea\u00e7\u00f5es \u2014 de novo, nada muito diferente do Uno em sua vers\u00e3o semelhante. Mesmo os freios dianteiros a disco s\u00f3lido, n\u00e3o ventilado, n\u00e3o causam preocupa\u00e7\u00e3o em um carro t\u00e3o leve.<\/p>\n<p>Afinal, o Mobi vale a pena? Depende: a resposta envolve uma breve compara\u00e7\u00e3o com alguns de seus advers\u00e1rios.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>Concorrente mais direto, o VW Up \u00e9 um carro mais moderno e eficiente em termos t\u00e9cnicos, como no econ\u00f4mico motor, e tem porta-malas bem maior<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>O mais direto, o\u00a0Up, \u00e9 um carro mais moderno e eficiente em termos t\u00e9cnicos, como no econ\u00f4mico motor de tr\u00eas cilindros com 75\/82 cv ou no melhor comando de transmiss\u00e3o. S\u00e3o similares em espa\u00e7o, mas o VW tem porta-malas maior em 70 litros (285 l). Diferen\u00e7a tamb\u00e9m em suspens\u00e3o: mais firme, a do Up favorece a estabilidade, mas perde em conforto. A vers\u00e3o Cross Up, com adere\u00e7os &#8220;aventureiros&#8221;, mant\u00e9m a mec\u00e2nica (suspens\u00e3o inclusa) de outras vers\u00f5es, ao contr\u00e1rio do Mobi Way. Mais cara (R$ 47.690), ela tem conte\u00fado similar ao do Fiat avaliado e acrescenta fixa\u00e7\u00e3o <a href=\"https:\/\/autolivraria.com.br\/bc\/glossario-i\/#isof\" target=\"_blank\">Isofix<\/a> para cadeira infantil.<\/p>\n<p>Outra op\u00e7\u00e3o, o Ford Ka, n\u00e3o oferece vers\u00e3o &#8220;aventureira&#8221; como o Way e o Cross. Seu comprimento quase 30 cm maior resulta em espa\u00e7o adicional para passageiros, enquanto o porta-malas de 257 litros fica entre os desses modelos. Ponto alto \u00e9 o\u00a0motor mais potente da classe (80\/85 cv), com\u00a0desempenho superior ao do Mobi e\u00a0consumo moderado, embora a vibra\u00e7\u00e3o t\u00edpica do tr\u00eas-cilindros fique bem presente.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-11' class='gallery galleryid-75425 gallery-columns-1 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-21.jpg'><img decoding=\"async\" width=\"696\" height=\"464\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-21-696x464.jpg\" class=\"attachment-large size-large lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 696px; --smush-placeholder-aspect-ratio: 696\/464;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-12' class='gallery galleryid-75425 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-20.jpg'><img decoding=\"async\" width=\"340\" height=\"227\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-20-340x227.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/227;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-22.jpg'><img decoding=\"async\" width=\"340\" height=\"227\" data-src=\"https:\/\/autolivraria.com.br\/bc\/wp-content\/uploads\/2016\/07\/Fiat-Mobi-Way-On-22-340x227.jpg\" class=\"attachment-medium size-medium lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 340px; --smush-placeholder-aspect-ratio: 340\/227;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: center;\"><em>Conforto do rodar em pisos de m\u00e1 qualidade e amplo v\u00e3o livre do solo s\u00e3o destaques, mas a estabilidade se ressente da altura e da maciez do Way<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Com menor altura de rodagem e pneus 195\/55 R 15, o Ka SEL que avaliamos supera facilmente o Mobi em comportamento din\u00e2mico, embora sem a mesma aptid\u00e3o para pisos irregulares. Essa vers\u00e3o, que vem de s\u00e9rie at\u00e9 com <a href=\"https:\/\/autolivraria.com.br\/bc\/glossario-c\/#esp\" target=\"_blank\">controle eletr\u00f4nico de estabilidade<\/a>, custa mais: R$ 48.140. O Ka mais pr\u00f3ximo em pre\u00e7o ao Fiat testado seria o SE Plus (R$ 44.390), que traz a mais que o Mobi controle el\u00e9trico de vidros traseiros e fixa\u00e7\u00f5es Isofix, deixando de fora far\u00f3is de neblina e rodas de alum\u00ednio.<\/p>\n<p>&nbsp;<\/p>\n<div class='code-block code-block-7' style='margin: 28px auto; text-align: center; display: block; clear: both;'>\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<!-- AL-quadrado -->\n<ins class=\"adsbygoogle\"\n     style=\"display:block\"\n     data-ad-client=\"ca-pub-1914799802606213\"\n     data-ad-slot=\"5683066082\"\n     data-ad-format=\"auto\"\n     data-full-width-responsive=\"true\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/div>\n\n<p>&nbsp;<\/p>\n<p>Colocar\u00edamos ainda entre as alternativas o <a href=\"https:\/\/autolivraria.com.br\/bc\/tag\/march-sv\" target=\"_blank\">Nissan March SV<\/a>, tamb\u00e9m de tr\u00eas cilindros (77 cv) e com ajuste de suspens\u00e3o voltado ao conforto. N\u00e3o t\u00e3o moderno quanto Up e Ka em desenho, est\u00e1 mais pr\u00f3ximo do segundo em comprimento e espa\u00e7o traseiro e oferece porta-malas razo\u00e1vel, 265\u00a0litros. Nossas medi\u00e7\u00f5es apontaram desempenho compar\u00e1vel ao do Mobi e consumo bastante bom. O March custa R$ 44.690 sem rodas de alum\u00ednio. Vale notar que os tr\u00eas rivais trazem assist\u00eancia el\u00e9trica de dire\u00e7\u00e3o e preaquecimento de \u00e1lcool para partida a frio, ausentes do Fiat.<\/p>\n<p>O que se pode concluir das compara\u00e7\u00f5es? Se suas prioridades ao comprar um hatch pequeno forem dimens\u00f5es bem compactas, rodar confort\u00e1vel, aptid\u00e3o para terrenos de m\u00e1 qualidade e mec\u00e2nica consagrada, o Mobi Way On pode ser boa op\u00e7\u00e3o. Mas \u00e9 preciso aceitar s\u00e9rias limita\u00e7\u00f5es de espa\u00e7o traseiro e para bagagem, estabilidade s\u00f3 razo\u00e1vel e desvantagens consistentes em desempenho e consumo diante do Up, que compartilha a praticidade do reduzido comprimento. Se tamanho n\u00e3o for problema, alternativas como Ka e March re\u00fanem bons argumentos sem se afastar da faixa de pre\u00e7o do novo Fiat.<\/p>\n<table border=\"0\">\n<tbody>\n<tr>\n<td><a href='https:\/\/autolivraria.com.br\/bc\/avaliacoes\/' class='small-button smallsilver'>Mais Avalia\u00e7\u00f5es<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<div class='et-box et-shadow'>\n\t\t\t\t\t<div class='et-box-content'><h2>Coment\u00e1rio t\u00e9cnico<\/h2>\n<p>\u2022 Embora derivado da arquitetura do Uno, o Mobi tem muito pouco em comum com ele em termos de estrutura. Imagens apresentadas pela Fiat apontam que\u00a0apenas uma se\u00e7\u00e3o dianteira, que inclui as longarinas, e os pontos de apoio da suspens\u00e3o traseira s\u00e3o iguais.<\/p>\n<p>\u2022 O conhecido motor Fire deixa de fora t\u00e9cnicas atuais como bloco de alum\u00ednio, quatro v\u00e1lvulas por cilindro e <a href=\"https:\/\/autolivraria.com.br\/bc\/glossario-v\/#vari\" target=\"_blank\">varia\u00e7\u00e3o de tempo de abertura<\/a> das v\u00e1lvulas. O acionamento do comando usa correia dentada. Seu ponto alto \u00e9 a brilhante <a href=\"https:\/\/autolivraria.com.br\/bc\/glossario-r\/#rela\" target=\"_blank\">rela\u00e7\u00e3o r\/l<\/a> de 0,23, uma das melhores do mercado, que resulta em opera\u00e7\u00e3o muito suave.<\/p>\n<p>\u2022 O c\u00e1lculo de transmiss\u00e3o (para qualquer vers\u00e3o do Mobi, exceto a Easy, que tem pneus de menor di\u00e2metro) prev\u00ea velocidade m\u00e1xima em quarta marcha com o motor perto de 6.000 rpm, pouco abaixo da pot\u00eancia m\u00e1xima (6.250 rpm). Essa defini\u00e7\u00e3o\u00a0permite regime moderado em quinta para um motor de 1,0 litro, como 3.850 rpm a 120 km\/h.<\/p>\n<p>\u2022 A suspens\u00e3o do Way (com ou sem o sufixo On) \u00e9 a \u00fanica da linha com estabilizador dianteiro (atr\u00e1s, nenhuma tem), decis\u00e3o acertada para conter a inclina\u00e7\u00e3o da carroceria sem necessitar de molas mais firmes. Comparado ao Like, o Way tem 15 mm a mais de v\u00e3o livre do solo, todos obtidos na suspens\u00e3o, pois usa pneus iguais em medida 175\/65 R 14 (e de mesmo tipo, para uso predominante em asfalto). N\u00e3o h\u00e1 diferen\u00e7as em rela\u00e7\u00f5es de marcha e de diferencial. Conforme dados de f\u00e1brica, a vers\u00e3o obt\u00e9m velocidade m\u00e1xima 2 km\/h menor que a do Like, pela perda aerodin\u00e2mica decorrente da maior altura, mas preserva os n\u00fameros de acelera\u00e7\u00e3o e de consumo pelos dados do Inmetro.<\/p><\/div><\/div>\n<p>&nbsp;<\/p>\n<div class='et-box et-shadow'>\n\t\t\t\t\t<div class='et-box-content'><h2>Ficha t\u00e9cnica<\/h2>\n<table id=\"table61\" border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"3\">\n<tbody>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Motor<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Posi\u00e7\u00e3o<\/td>\n<td valign=\"top\" width=\"50%\">transversal<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Cilindros<\/td>\n<td valign=\"top\" width=\"50%\">4 em linha<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Material do bloco\/cabe\u00e7ote<\/td>\n<td valign=\"top\" width=\"50%\">ferro fundido\/alum\u00ednio<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Comando de v\u00e1lvulas<\/td>\n<td width=\"50%\">no cabe\u00e7ote<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">V\u00e1lvulas por cilindro<\/td>\n<td width=\"50%\">2<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Di\u00e2metro e curso<\/td>\n<td width=\"50%\">70 x 64,9 mm<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Cilindrada<\/td>\n<td width=\"50%\">999 cm\u00b3<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Taxa de compress\u00e3o<\/td>\n<td width=\"50%\">12,15:1<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Alimenta\u00e7\u00e3o<\/td>\n<td width=\"50%\">inje\u00e7\u00e3o multiponto sequencial<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Pot\u00eancia m\u00e1xima (gas.\/\u00e1lc.)<\/td>\n<td width=\"50%\">73\/75 cv a 6.250 rpm<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Torque m\u00e1ximo (gas.\/\u00e1lc.)<\/td>\n<td width=\"50%\">9,5\/9,9 m.kgf a 3.850 rpm<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Pot\u00eancia espec\u00edfica (gas.\/\u00e1lc.)<\/td>\n<td valign=\"top\" width=\"50%\">73,1\/75,1 cv\/l<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Transmiss\u00e3o<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Tipo de caixa e marchas<\/td>\n<td valign=\"top\" width=\"50%\">manual \/ 5<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\">Rela\u00e7\u00e3o e velocidade por 1.000 rpm<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">1\u00aa.<\/td>\n<td valign=\"top\" width=\"50%\">4,27 \/ 6 km\/h<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">2\u00aa.<\/td>\n<td valign=\"top\" width=\"50%\">2,32 \/ 11 km\/h<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">3\u00aa.<\/td>\n<td valign=\"top\" width=\"50%\">1,44 \/ 18\u00a0 km\/h<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">4\u00aa.<\/td>\n<td valign=\"top\" width=\"50%\">1,03 \/ 25 km\/h<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">5\u00aa.<\/td>\n<td valign=\"top\" width=\"50%\">0,84 \/ 31 km\/h<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Rela\u00e7\u00e3o de diferencial<\/td>\n<td valign=\"top\" width=\"50%\">4,20<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Regime a 120 km\/h<\/td>\n<td valign=\"top\" width=\"50%\">3.850 rpm (5\u00aa.)<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Regime \u00e0 vel. m\u00e1xima informada\u00a0 (gas.\/\u00e1lc.)<\/td>\n<td valign=\"top\" width=\"50%\">5.950\/6.000 rpm (4\u00aa.)<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Tra\u00e7\u00e3o<\/td>\n<td valign=\"top\" width=\"50%\">dianteira<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Freios<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Dianteiros<\/td>\n<td valign=\"top\" width=\"50%\">a disco (257 mm \u00f8)<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Traseiros<\/td>\n<td valign=\"top\" width=\"50%\">a tambor (185 mm \u00f8)<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Antitravamento (ABS)<\/td>\n<td valign=\"top\" width=\"50%\">sim<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Dire\u00e7\u00e3o<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Sistema<\/td>\n<td width=\"50%\">pinh\u00e3o e cremalheira<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Assist\u00eancia<\/td>\n<td width=\"50%\">hidr\u00e1ulica<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Di\u00e2metro de giro<\/td>\n<td width=\"50%\">10,0 m<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Suspens\u00e3o<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Dianteira<\/td>\n<td valign=\"top\" width=\"50%\">independente, McPherson, mola helicoidal<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Traseira<\/td>\n<td valign=\"top\" width=\"50%\">eixo de tor\u00e7\u00e3o, mola helicoidal<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Estabilizador<\/td>\n<td valign=\"top\" width=\"50%\">dianteiro<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Rodas<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Dimens\u00f5es<\/td>\n<td width=\"50%\">5,5 x 14 pol<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Pneus<\/td>\n<td width=\"50%\">175\/65 R 14<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Dimens\u00f5es<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Comprimento<\/td>\n<td valign=\"top\" width=\"50%\">3,596 m<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Largura<\/td>\n<td valign=\"top\" width=\"50%\">1,685 m<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Altura<\/td>\n<td valign=\"top\" width=\"50%\">1,55 m<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Entre-eixos<\/td>\n<td valign=\"top\" width=\"50%\">2,305 m<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Bitola dianteira<\/td>\n<td valign=\"top\" width=\"50%\">1,396 m<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Bitola traseira<\/td>\n<td valign=\"top\" width=\"50%\">1,40 m<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Coeficiente aerodin\u00e2mico (Cx)<\/td>\n<td valign=\"top\" width=\"50%\">ND<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Capacidades e peso<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Tanque de combust\u00edvel<\/td>\n<td valign=\"top\" width=\"50%\">47 l<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Compartimento de bagagem<\/td>\n<td valign=\"top\" width=\"50%\">215 l<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Peso em ordem de marcha<\/td>\n<td valign=\"top\" width=\"50%\">966 kg<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Rela\u00e7\u00e3o peso-pot\u00eancia (gas.\/\u00e1lc.)<\/td>\n<td valign=\"top\" width=\"50%\">13,2\/12,9 kg\/cv<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Garantia<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Prazo<\/td>\n<td valign=\"top\" width=\"50%\">3 anos sem limite de quilometragem<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\"><strong>Carro avaliado<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Ano-modelo<\/td>\n<td valign=\"top\" width=\"50%\">2017<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Pneus<\/td>\n<td valign=\"top\" width=\"50%\">Pirelli Cinturato P1<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">Quilometragem inicial<\/td>\n<td valign=\"top\" width=\"50%\">1.500 km<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" width=\"50%\">Dados do fabricante; ND = n\u00e3o dispon\u00edvel<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O novo pequeno passa por avalia\u00e7\u00e3o com medi\u00e7\u00f5es e revela o que pode oferecer diante de VW Up e outros<\/p>\n","protected":false},"author":6,"featured_media":75428,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[3,3611,1827],"tags":[80,36,57,4027,4031],"class_list":["post-75425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avaliacao","category-avaliacao-completa","category-fiat-avaliacao","tag-avaliacao-2","tag-avaliacao-completa","tag-fiat","tag-mobi","tag-mobi-way"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/posts\/75425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/comments?post=75425"}],"version-history":[{"count":0,"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/posts\/75425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/media\/75428"}],"wp:attachment":[{"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/media?parent=75425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/categories?post=75425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/autolivraria.com.br\/bc\/wp-json\/wp\/v2\/tags?post=75425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}